{"id":4248,"date":"2022-08-16T02:41:19","date_gmt":"2022-08-16T00:41:19","guid":{"rendered":"https:\/\/socialmonk.net\/contacto\/"},"modified":"2023-06-21T00:44:47","modified_gmt":"2023-06-20T22:44:47","slug":"contacto","status":"publish","type":"page","link":"https:\/\/socialmonk.net\/br\/contacto\/","title":{"rendered":"Contato"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4248\" class=\"elementor elementor-4248 elementor-1226\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87e5911 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87e5911\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f36036\" data-id=\"4f36036\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4379a9 elementor-widget elementor-widget-html\" data-id=\"e4379a9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- REFERSION TRACKING: BEGIN --> \n<script src=\"\/\/socialmonk.refersion.com\/tracker\/v3\/pub_35035391f7697172acf3.js\"><\/script>\n<script>_refersion(function(){ _rfsn._setSource(\"CHARGEBEE\"); });<\/script>\n<!-- REFERSION TRACKING: END --> \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c66a8e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c66a8e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-188d3f97\" data-id=\"188d3f97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6584e0c7 elementor-widget elementor-widget-heading\" data-id=\"6584e0c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc10c3c elementor-widget elementor-widget-heading\" data-id=\"3fc10c3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00favidas? Nos escreva uma mensagem.<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fbae570 elementor-widget elementor-widget-text-editor\" data-id=\"5fbae570\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ficamos felizes em ouvir de voc\u00ea.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54f938af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54f938af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55b76d20\" data-id=\"55b76d20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a07d70e elementor-widget elementor-widget-image\" data-id=\"a07d70e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-1024x684.jpg\" class=\"attachment-large size-large wp-image-9519\" alt=\"\" srcset=\"https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-1024x684.jpg 1024w, https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-300x200.jpg 300w, https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-768x513.jpg 768w, https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-1536x1025.jpg 1536w, https:\/\/socialmonk.net\/wp-content\/uploads\/2023\/06\/arlington-research-Kz8nHVg_tGI-unsplash-2048x1367.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-716db215 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"716db215\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-522f1e60\" data-id=\"522f1e60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d2b1d9b elementor-widget elementor-widget-heading\" data-id=\"3d2b1d9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Formul\u00e1rio de contato<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9e0e0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9e0e0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e55ae9\" data-id=\"8e55ae9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eaf016 elementor-widget elementor-widget-wpforms\" data-id=\"1eaf016\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-1290\"><form id=\"wpforms-form-1290\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1290\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/br\/wp-json\/wp\/v2\/pages\/4248\" data-token=\"63fef5234102bab19065ae274f7e1192\" data-token-time=\"1778678137\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1290-field_4-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline wpforms-conditional-trigger\" data-field-id=\"4\"><label class=\"wpforms-field-label\">Eu j\u00e1 sou um cliente <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1290-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_4_1\" name=\"wpforms[fields][4]\" value=\"Sim\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_4_1\">Sim<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_4_2\" name=\"wpforms[fields][4]\" value=\"N\u00e3o\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_4_2\">N\u00e3o<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_1-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"1\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_1\">Assunto <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1290-field_1\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][1]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Por favor selecciona ...<\/option><option value=\"Que crescimento posso esperar?\" >Que crescimento posso esperar?<\/option><option value=\"Posso continuar a usar a minha conta Instagram?\" >Posso continuar a usar a minha conta Instagram?<\/option><option value=\"O que est\u00e1s a fazer exactamente no meu perfil?\" >O que est\u00e1s a fazer exactamente no meu perfil?<\/option><option value=\"Quando \u00e9 que o meu perfil vai ser processado?\" >Quando \u00e9 que o meu perfil vai ser processado?<\/option><option value=\"Como posso definir filtros para a l\u00edngua \/ g\u00e9nero?\" >Como posso definir filtros para a l\u00edngua \/ g\u00e9nero?<\/option><option value=\"Rescis\u00e3o\" >Rescis\u00e3o<\/option><option value=\"Outro pedido\" >Outro pedido<\/option><\/select><\/div><div id=\"wpforms-1290-field_34-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-hide wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_34\">Assunto <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1290-field_34\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][34]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Por favor selecciona ...<\/option><option value=\"Que crescimento posso esperar?\" >Que crescimento posso esperar?<\/option><option value=\"Posso continuar a usar a minha conta Instagram?\" >Posso continuar a usar a minha conta Instagram?<\/option><option value=\"O que est\u00e1s a fazer exactamente no meu perfil?\" >O que est\u00e1s a fazer exactamente no meu perfil?<\/option><option value=\"Outro pedido\" >Outro pedido<\/option><\/select><\/div><div id=\"wpforms-1290-field_38-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"38\" style=\"display:none;\"><div id=\"wpforms-1290-field_38\"><span style=\"font-size:18px\">\r\n\r\nCome\u00e7amos sempre por nos aproximarmos lentamente dos limites estabelecidos pela Instagram. Por isso o crescimento deve tornar-se cada vez melhor com o passar do tempo. No entanto, o crescimento tamb\u00e9m depende de muitos outros factores, tais como o desenho do perfil, nicho e idade da conta.<br \/>\r\nDependendo da subscri\u00e7\u00e3o reservada, o crescimento no Plano Starter at\u00e9 1,000, no Plano Standard at\u00e9 2,000 e no Plano Business at\u00e9 3,000 seguidores por m\u00eas.\r\n\r\n<br \/><br \/>\r\n\r\nA tua pergunta n\u00e3o foi respondida? Ent\u00e3o d\u00e1 uma vista de olhos ao nosso <a href=\"https:\/\/socialmonk.net\/br\/faq\" target=\"_blank\">FAQ<\/a> ou escreve-nos apenas uma mensagem.\r\n\r\n<\/span><br \/><br \/><\/div><\/div><div id=\"wpforms-1290-field_11-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"11\" style=\"display:none;\"><div id=\"wpforms-1290-field_11\"><span style=\"font-size:18px\">\r\n\r\nPodes continuar a usar a tua conta Instagram em toda a sua extens\u00e3o enquanto estamos a processar o teu pedido. Apenas te pedimos que nos deixes o seguinte dos novos perfis.\r\n\r\n<br \/><br \/>\r\n\r\nA tua pergunta n\u00e3o foi respondida? Ent\u00e3o d\u00e1 uma vista de olhos ao nosso <a href=\"https:\/\/socialmonk.net\/br\/faq\" target=\"_blank\">FAQ<\/a> ou escreve-nos apenas uma mensagem.\r\n\r\n<\/span><br \/><br \/><\/div><\/div><div id=\"wpforms-1290-field_14-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"14\" style=\"display:none;\"><div id=\"wpforms-1290-field_14\"><span style=\"font-size:18px\">\r\n\r\nVisamos o teu perfil, entre outras coisas, seguindo os perfis do teu grupo alvo especificado, acompanhando ap\u00f3s algum tempo, ligando mensagens e olhando para hist\u00f3rias. Para al\u00e9m do conte\u00fado de alta qualidade, este \u00e9 na nossa experi\u00eancia o m\u00e9todo mais eficaz para o crescimento org\u00e2nico. No entanto, o crescimento tamb\u00e9m depende de muitos outros factores, como o layout do perfil, a ind\u00fastria, o nicho, o alcance e a taxa de interac\u00e7\u00e3o. Uma vez que nunca compramos seguidores, o teu n\u00famero de subscri\u00e7\u00e3o n\u00e3o ir\u00e1 aumentar subitamente em v\u00e1rios milhares de subscritores. Realizamos todas as actividades manualmente. Isto \u00e9, seguir\/de-seguir, esquerda e vista de hist\u00f3ria. O teu perfil ir\u00e1 crescer mais lentamente, mas organicamente com seguidores reais do teu grupo alvo.\r\n\r\n<br \/><br \/>\r\n\r\nA tua pergunta n\u00e3o foi respondida? Ent\u00e3o d\u00e1 uma vista de olhos ao nosso <a href=\"https:\/\/socialmonk.net\/br\/faq\" target=\"_blank\">FAQ<\/a> ou escreve-nos apenas uma mensagem.\r\n\r\n<\/span><br \/><br \/><\/div><\/div><div id=\"wpforms-1290-field_23-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><div id=\"wpforms-1290-field_23\"><span style=\"font-size:18px\">\r\n\r\nNormalmente come\u00e7amos a editar o teu perfil em 24 horas. O pr\u00e9-requisito para isto \u00e9 que perfis e hashtags similares sejam armazenados no portal <a href=\"https:\/\/socialmonk.chargebeeportal.com\/portal\" target=\"_blank\" rel=\"noopener\">portais do cliente<\/a>.\r\n\r\n<br \/><br \/>\r\n\r\nA tua pergunta n\u00e3o foi respondida? Ent\u00e3o d\u00e1 uma vista de olhos ao nosso <a href=\"https:\/\/socialmonk.net\/br\/faq\" target=\"_blank\">FAQ<\/a> ou escreve-nos apenas uma mensagem.\r\n\r\n<\/span><br \/><br \/>\r\n\r\n<\/div><\/div><div id=\"wpforms-1290-field_29-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"29\" style=\"display:none;\"><div id=\"wpforms-1290-field_29\"><span style=\"font-size:18px\">\r\n\r\nPara activares o filtro por idioma e\/ou g\u00e9nero, basta enviares-nos o seguinte formul\u00e1rio. Por favor nota que estes filtros s\u00f3 ser\u00e3o aplicados se tiveres subscrito o Pacote Empresarial.\r\n\r\n<\/span><br \/><br \/><\/div><\/div><div id=\"wpforms-1290-field_30-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"30\" style=\"display:none;\"><label class=\"wpforms-field-label\">Filtro para a l\u00edngua<\/label><ul id=\"wpforms-1290-field_30\"><li class=\"choice-7 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_7\" name=\"wpforms[fields][30]\" value=\"Todos os idiomas\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_7\">Todos os idiomas<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_6\" name=\"wpforms[fields][30]\" value=\"Portugu\u00eas\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_6\">Portugu\u00eas<\/label><\/li><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_1\" name=\"wpforms[fields][30]\" value=\"Alem\u00e3o\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_1\">Alem\u00e3o<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_2\" name=\"wpforms[fields][30]\" value=\"Ingl\u00eas\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_2\">Ingl\u00eas<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_3\" name=\"wpforms[fields][30]\" value=\"Espanhol\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_3\">Espanhol<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_4\" name=\"wpforms[fields][30]\" value=\"Franc\u00eas\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_4\">Franc\u00eas<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_30_5\" name=\"wpforms[fields][30]\" value=\"Italiano\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_30_5\">Italiano<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_31-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"31\" style=\"display:none;\"><label class=\"wpforms-field-label\">Filtro para g\u00e9nero<\/label><ul id=\"wpforms-1290-field_31\"><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_31_3\" name=\"wpforms[fields][31]\" value=\"Masculino e Feminino\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_31_3\">Masculino e Feminino<\/label><\/li><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_31_1\" name=\"wpforms[fields][31]\" value=\"Feminino\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_31_1\">Feminino<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_31_2\" name=\"wpforms[fields][31]\" value=\"Masculino\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_31_2\">Masculino<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_2-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"2\" style=\"display:none;\"><div id=\"wpforms-1290-field_2\"><span style=\"font-size:18px\">\r\n\r\n\u00c9 uma pena que queiras deixar-nos. Se n\u00e3o est\u00e1s satisfeito com o crescimento do teu Instagram, existem normalmente as seguintes raz\u00f5es:\r\n\r\n<strong><\/strong><br \/>\r\n\r\n<ul>\r\n<li>\r\n\r\nOs teus perfis e\/ou hashtags semelhantes s\u00e3o demasiado gerais e n\u00e3o suficientemente espec\u00edficos. Podes alterar a tua informa\u00e7\u00e3o a qualquer momento no teu <a href=\"https:\/\/socialmonk.chargebeeportal.com\/portal\" target=\"_blank\" rel=\"noopener\">Portal do cliente<\/a>.\r\n\r\n<\/li>\r\n\r\n<li>\r\n\r\nOs teus perfis especificados t\u00eam demasiados seguidores (>50.000 seguidores). \u00c9 melhor escolheres perfis com at\u00e9 10.000 seguidores.\r\n\r\n<\/li>\r\n<li>\r\n\r\nA qualidade do teu perfil e\/ou das tuas mensagens. Por favor l\u00ea a nossa <a href=\"https:\/\/socialmonk.net\/br\/10-dicas-para-uma-conta-instagram-bem-sucedida\/\" target=\"_blank\">10 dicas para uma conta Instagram bem sucedida<\/a>.\r\n\r\n<\/li>\r\n<\/ul>\r\n\r\nSe ainda quiseres cancelar, basta preencheres o formul\u00e1rio abaixo e n\u00f3s cancelaremos a tua subscri\u00e7\u00e3o. Tamb\u00e9m pode cancelar a subscri\u00e7\u00e3o em qualquer altura no <a href=\"https:\/\/socialmonk.chargebeeportal.com\/portal\" target=\"_blank\" rel=\"noopener\">Portal do cliente<\/a>.\r\n\r\n<\/span><\/div><\/div><div id=\"wpforms-1290-field_18-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"18\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\">Confirma\u00e7\u00e3o do cancelamento <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1290-field_18\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1290-field_18_1\" name=\"wpforms[fields][18][]\" value=\"Eu n\u00e3o quero implementar as optimiza\u00e7\u00f5es e cancelar a minha subscri\u00e7\u00e3o.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_18_1\">Eu n\u00e3o quero implementar as optimiza\u00e7\u00f5es e cancelar a minha subscri\u00e7\u00e3o.<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_41-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_41\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-1290-field_41\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][41][first]\" required><label for=\"wpforms-1290-field_41\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-1290-field_41-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][41][last]\" required><label for=\"wpforms-1290-field_41-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nachname<\/label><\/div><\/div><\/div><div id=\"wpforms-1290-field_3-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"3\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_3\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1290-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" spellcheck=\"false\" required><div class=\"wpforms-field-description\">Por favor insere o email com o qual a subscri\u00e7\u00e3o foi efectuada.<\/div><\/div><div id=\"wpforms-1290-field_28-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-hide\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_28\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1290-field_28\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][28]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1290-field_8-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"8\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_8\">Nome do Perfil Instagram <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1290-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" required><div class=\"wpforms-field-description\">Por favor presta aten\u00e7\u00e3o \u00e0 ortografia correcta, por exemplo, mai\u00fasculas e min\u00fasculas e caracteres especiais.<\/div><\/div><div id=\"wpforms-1290-field_43-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger\" data-field-id=\"43\" style=\"display:none;\"><label class=\"wpforms-field-label\">Quando \u00e9 que queres desistir? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1290-field_43\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_43_1\" name=\"wpforms[fields][43]\" value=\"Na data mais pr\u00f3xima poss\u00edvel\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_43_1\">Na data mais pr\u00f3xima poss\u00edvel<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-1290-field_43_2\" name=\"wpforms[fields][43]\" value=\"Data espec\u00edfica\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_43_2\">Data espec\u00edfica<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_42-container\" class=\"wpforms-field wpforms-field-date-time wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"42\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_42\">Data de cancelamento pretendida <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-1290-field_42\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-small\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][42][date]\" placeholder=\"por favor selecciona um\" required><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><div class=\"wpforms-field-description\">Por favor introduz a data em que desejas cancelar a subscri\u00e7\u00e3o. <\/div><\/div><div id=\"wpforms-1290-field_15-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"15\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_15\">Motivo da rescis\u00e3o <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1290-field_15\" class=\"wpforms-field-medium wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"\" name=\"wpforms[fields][15]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Por favor selecciona ...<\/option><option value=\"Demasiado caro\" >Demasiado caro<\/option><option value=\"N\u00e3o satisfeito com o crescimento\" >N\u00e3o satisfeito com o crescimento<\/option><option value=\"Pausa\" >Pausa<\/option><option value=\"Outro motivo\" >Outro motivo<\/option><\/select><\/div><div id=\"wpforms-1290-field_16-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"16\" style=\"display:none;\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1290-field_16\">Motivo da rescis\u00e3o <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1290-field_16\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][16]\" placeholder=\"Por favor indica o motivo da rescis\u00e3o\" required><\/div><div id=\"wpforms-1290-field_32-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-hide\" data-field-id=\"32\"><label class=\"wpforms-field-label\" for=\"wpforms-1290-field_32\">A tua mensagem <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-1290-field_32\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][32]\" required><\/textarea><\/div><div id=\"wpforms-1290-field_50-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"50\"><label class=\"wpforms-field-label wpforms-label-hide\">Datenschutz <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-1290-field_50\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1290-field_50_1\" name=\"wpforms[fields][50][]\" value=\"Eu tomei nota da &lt;a href=&quot;https:\/\/socialmonk.net\/br\/privacy-policy&quot; target=&quot;_blank&quot;&gt;pol\u00edtica de privacidade&lt;\/a&gt;.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1290-field_50_1\">Eu tomei nota da <a href=\"https:\/\/socialmonk.net\/br\/privacy-policy\" target=\"_blank\">pol\u00edtica de privacidade<\/a>.<\/label><\/li><\/ul><\/div><div id=\"wpforms-1290-field_44-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"44\"><input type=\"hidden\" id=\"wpforms-1290-field_44\" name=\"wpforms[fields][44]\" value=\"BR\"><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-1290-field-hp\" class=\"wpforms-field-label\">Website<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-1290-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1290\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/pages\/4248\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1290\" class=\"wpforms-submit\" data-alt-text=\"Enviar...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/socialmonk.net\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contato D\u00favidas? Nos escreva uma mensagem. Ficamos felizes em ouvir de voc\u00ea. Formul\u00e1rio de contato<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"class_list":["post-4248","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/pages\/4248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/comments?post=4248"}],"version-history":[{"count":7,"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/pages\/4248\/revisions"}],"predecessor-version":[{"id":9682,"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/pages\/4248\/revisions\/9682"}],"wp:attachment":[{"href":"https:\/\/socialmonk.net\/br\/wp-json\/wp\/v2\/media?parent=4248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}